{"id":783,"date":"2015-03-16T12:58:07","date_gmt":"2015-03-16T12:58:07","guid":{"rendered":"http:\/\/www.spuerhundeschule.de\/blog\/?p=783"},"modified":"2015-09-02T17:24:58","modified_gmt":"2015-09-02T17:24:58","slug":"einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1","status":"publish","type":"post","link":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/","title":{"rendered":"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1"},"content":{"rendered":"<h1>Am vergangenem Mittwoch, fand Teil 1 der <strong>Einsatz\u00fcberpr\u00fcfung<\/strong> unserer <strong>Sprengstoffsp\u00fcrhunde-Teams<\/strong> zur Qualit\u00e4tssicherung in einem Pirnaer Hotel statt.<\/h1>\n<p>Hierbei wurde f\u00fcr 2 Teams die j\u00e4hrliche Einsatzf\u00e4higkeit bescheinigt. Zwar m\u00fcssen unsere Sprengstoffsp\u00fcrhunde eine j\u00e4hrlich externe Pr\u00fcfung bei einer Beh\u00f6rde absolvieren, dennoch m\u00fcssen die Hunde und Hundef\u00fchrer sich einer Qualit\u00e4tssicherung unterziehen. Einsatzhunde werden wiederholend f\u00fcr den Einsatz vorbereiten.<\/p>\n<p>Was bedeutet das im Einzelnen? Einsatz\u00fcberpr\u00fcfung ist die konkrete Ermittlung, ob bei Sprengstoffsp\u00fcrhunden bzw. Hundeeins\u00e4tzen bestimmte Bedingungen erf\u00fcllt sind, z. B. Bedingungen nach DIN\/EN. Sie ist ein wesentlicher Teil des Qualit\u00e4tsmanagements. Die Einsatz\u00fcberpr\u00fcfung dient also zum Feststellen, inwieweit z. B. ein Sprengstoffsp\u00fcrhunde-Team die Qualit\u00e4ts-Anforderung erf\u00fcllt. Die \u00dcberpr\u00fcfung der Hunde findet je nach Einsatzgebiet anhand harter Fakten und voreingenommen statt.<\/p>\n<p>Jedes externe Sp\u00fcrhunde-Team mit dem wir eine Kooperation eingegangen sind, muss sich unabdingbar dieser Qualit\u00e4ts\u00fcberpr\u00fcfung j\u00e4hrlich unterziehen! Alle Einsatz-Teams bekommen dies in Form eines Zertifikats bzw. Leistungsnachweis bescheinigt.<\/p>\n<p><a href=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-785 alignleft\" src=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-300x225.jpg\" alt=\"Hundetrainerschein\" width=\"300\" height=\"225\" srcset=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-300x225.jpg 300w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-150x113.jpg 150w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-50x38.jpg 50w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0 <a href=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-789\" src=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2-300x225.jpg\" alt=\"Hundetrainerschein (2)\" width=\"306\" height=\"229\" srcset=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2-300x225.jpg 300w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2-150x113.jpg 150w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2-50x38.jpg 50w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundetrainerschein-2.jpg 800w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-790\" src=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1-300x225.jpg\" alt=\"Hundezertifikat1\" width=\"300\" height=\"225\" srcset=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1-300x225.jpg 300w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1-150x113.jpg 150w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1-50x38.jpg 50w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Hundezertifikat1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 <a href=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-791\" src=\"http:\/\/www.spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1-300x225.jpg\" alt=\"Einsatz\u00fcberpr\u00fcfung1\" width=\"307\" height=\"230\" srcset=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1-300x225.jpg 300w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1-150x113.jpg 150w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1-50x38.jpg 50w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2015\/03\/Einsatz\u00fcberpr\u00fcfung1.jpg 800w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/a><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Am vergangenem Mittwoch, fand Teil 1 der Einsatz\u00fcberpr\u00fcfung unserer Sprengstoffsp\u00fcrhunde-Teams zur Qualit\u00e4tssicherung in einem Pirnaer Hotel statt. Hierbei wurde f\u00fcr 2 Teams die j\u00e4hrliche Einsatzf\u00e4higkeit bescheinigt. Zwar m\u00fcssen unsere Sprengstoffsp\u00fcrhunde eine j\u00e4hrlich externe Pr\u00fcfung&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[27,8],"tags":[98,99,96,97,33],"class_list":["post-783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelle-einsaetze","category-sprengstoffspurhunde","tag-einsatzueberpruefung","tag-hunde","tag-hundetrainerschein","tag-sprengstoffhunde","tag-spuerhunde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1 - Sp\u00fcrhundeschule Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"K-9 Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/\"},\"author\":{\"name\":\"K-9 Admin\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/75d15ede555e697c66e026348098c381\"},\"headline\":\"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1\",\"datePublished\":\"2015-03-16T12:58:07+00:00\",\"dateModified\":\"2015-09-02T17:24:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/\"},\"wordCount\":182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/P1010752.jpg\",\"keywords\":[\"einsatz\u00fcberpr\u00fcfung\",\"hunde\",\"hundetrainerschein\",\"sprengstoffhunde\",\"sp\u00fcrhunde\"],\"articleSection\":[\"aktuelle Eins\u00e4tze\",\"Sprengstoffsp\u00fcrhunde\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/\",\"name\":\"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1 - Sp\u00fcrhundeschule Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/P1010752.jpg\",\"datePublished\":\"2015-03-16T12:58:07+00:00\",\"dateModified\":\"2015-09-02T17:24:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/P1010752.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/P1010752.jpg\",\"width\":4608,\"height\":2592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/sprengstoffspurhunde\\\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"name\":\"Sp\u00fcrhundeschule Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\",\"name\":\"K9 Detection Dog School Germany GmbH\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"width\":148,\"height\":150,\"caption\":\"K9 Detection Dog School Germany GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/75d15ede555e697c66e026348098c381\",\"name\":\"K-9 Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g\",\"caption\":\"K-9 Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1 - Sp\u00fcrhundeschule Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/","twitter_misc":{"Verfasst von":"K-9 Admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#article","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/"},"author":{"name":"K-9 Admin","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/75d15ede555e697c66e026348098c381"},"headline":"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1","datePublished":"2015-03-16T12:58:07+00:00","dateModified":"2015-09-02T17:24:58+00:00","mainEntityOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/"},"wordCount":182,"commentCount":0,"publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2014\/06\/P1010752.jpg","keywords":["einsatz\u00fcberpr\u00fcfung","hunde","hundetrainerschein","sprengstoffhunde","sp\u00fcrhunde"],"articleSection":["aktuelle Eins\u00e4tze","Sprengstoffsp\u00fcrhunde"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/","url":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/","name":"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1 - Sp\u00fcrhundeschule Blog","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#primaryimage"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2014\/06\/P1010752.jpg","datePublished":"2015-03-16T12:58:07+00:00","dateModified":"2015-09-02T17:24:58+00:00","breadcrumb":{"@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#primaryimage","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2014\/06\/P1010752.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2014\/06\/P1010752.jpg","width":4608,"height":2592},{"@type":"BreadcrumbList","@id":"https:\/\/spuerhundeschule.de\/blog\/sprengstoffspurhunde\/einsatzueberpruefung-der-eigenen-sprengstoffspuerhunde-teil-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spuerhundeschule.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Einsatz\u00fcberpr\u00fcfung der eigenen Sprengstoffsp\u00fcrhunde Teil 1"}]},{"@type":"WebSite","@id":"https:\/\/spuerhundeschule.de\/blog\/#website","url":"https:\/\/spuerhundeschule.de\/blog\/","name":"Sp\u00fcrhundeschule Blog","description":"","publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spuerhundeschule.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spuerhundeschule.de\/blog\/#organization","name":"K9 Detection Dog School Germany GmbH","url":"https:\/\/spuerhundeschule.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","width":148,"height":150,"caption":"K9 Detection Dog School Germany GmbH"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/75d15ede555e697c66e026348098c381","name":"K-9 Admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/585f10d0932e2835e8250ad0b1231e468cbc07ff696a3e2dd91233ce5196ccb8?s=96&d=mm&r=g","caption":"K-9 Admin"}}]}},"_links":{"self":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":0,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media\/453"}],"wp:attachment":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}