{"id":1786,"date":"2021-11-01T05:25:54","date_gmt":"2021-11-01T04:25:54","guid":{"rendered":"https:\/\/spuerhundeschule.de\/blog\/?p=1786"},"modified":"2021-11-01T05:51:05","modified_gmt":"2021-11-01T04:51:05","slug":"ruede-oder-huendin-welcher-hund-passt-zu-mir","status":"publish","type":"post","link":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/","title":{"rendered":"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir?"},"content":{"rendered":"<p>Die Entscheidung, einen Vierbeiner aufzunehmen oder anzuschaffen, wird h\u00e4ufig von der Frage begleitet: <em>Welches Geschlecht passt zu mir?<\/em><\/p>\n<p>Doch ist diese nicht so einfach zu beantworten. Viele Vorurteile rangen sich um vermeintliche Eigenschaften, die mit dem Geschlecht des Hundes einhergehen. Doch sind diese Merkmale h\u00e4ufig dem Charakter zuzuschreiben. Der wiederum variiert von Rasse zu Rasse.<\/p>\n<p><strong>Dennoch existieren zwischen H\u00fcndinnen und R\u00fcden durchaus Unterschiede<\/strong>. Nicht alle Eigenschaften k\u00f6nnen verallgemeinert werden. Doch sind sie, je nach Geschlecht, h\u00e4ufig anzutreffen. Weitergehende Lekt\u00fcre zum Beispiel auf <a href=\"https:\/\/naturwissenschaften24.com\/wie-nennt-man-einen-weiblichen-maennlichen-hund-tz14\/\">auf Naturwissenschaften24.com<\/a><\/p>\n<h2><u>M\u00f6gliche Probleme mit R\u00fcden<\/u><\/h2>\n<p>R\u00fcden sind besonders daf\u00fcr bekannt, ihr Revier zu markieren. Dieses Verhalten hat seinen Ursprung bei den m\u00e4nnlichen W\u00f6lfen. Sie tragen die Verantwortung, ihr Rudel zu sch\u00fctzen und zu versorgen. Es kann passieren, dass der R\u00fcde nicht nur w\u00e4hrend des Gassigehens, sondern auch in der Wohnung markiert. Sofern er drau\u00dfen uriniert, entscheidet er sich auch hier oft f\u00fcr die selben Stellen, die immer wieder aufs Neue markiert werden.<\/p>\n<p>Zudem neigen sie vor allem in jungen Jahren h\u00e4ufiger zur Kampfbereitschaft. Was die Agressivit\u00e4t bei m\u00e4nnlichen bzw. weiblichen Hunden anbelangt verweisen wir auf folgende Doktorarbeit der Uni M\u00fcnchen:<\/p>\n<p><a href=\"https:\/\/edoc.ub.uni-muenchen.de\/12044\/1\/Hoess_Patrizia.pdf\">https:\/\/edoc.ub.uni-muenchen.de\/12044\/1\/Hoess_Patrizia.pdf<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1789\" src=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser.png\" alt=\"welcher hund passt zu mir\" width=\"1200\" height=\"1920\" srcset=\"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser.png 1200w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser-188x300.png 188w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser-640x1024.png 640w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser-768x1229.png 768w, https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/hund-oder-huendin-was-ist-besser-960x1536.png 960w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2><u>M\u00f6gliche Probleme mit H\u00fcndinnen<\/u><\/h2>\n<p>H\u00fcndinnen dagegen sind vor allem w\u00e4hrend der L\u00e4ufigkeit schwer zu erziehen. Sofern diese eintritt, sind sie oft nicht bei der Sache und legen auch gereizteres Verhalten an den Tag. Setzt daraufhin der Eisprung ein, ist die H\u00fcndin f\u00fcr ungef\u00e4hr sechs bis zehn Tage ausschlie\u00dflich auf den R\u00fcden fixiert. Das liegt an der Paarungsbereitschaft, die damit einhergeht. Eine gut erzogene und gehorsame H\u00fcndin ist in dieser Zeit oft nicht wiederzuerkennen. M\u00f6glicherweise tritt sie anderen Weibchen gegen\u00fcber auch aggressiv auf oder neigt gar zum Bei\u00dfen. Um R\u00fcden ihre Paarungswilligkeit zu vermitteln, kann es sein, dass sie ebenfalls, \u00e4hnlich einem M\u00e4nnchen, markiert. Das tritt vor allem bei dominanten H\u00fcndinnen geh\u00e4uft auf.<\/p>\n<p>Sofern die H\u00fcndin nicht tats\u00e4chlich tr\u00e4chtig ist, setzt mehrere Wochen danach die Scheintr\u00e4chtigkeit ein. Der Ursprung liegt auch hier bei den weiblichen W\u00f6lfen. Sie haben die Aufgabe, sich um die Welpen der Leitw\u00f6lfin zu k\u00fcmmern. Dazu z\u00e4hlt, sie zu ern\u00e4hren und zu s\u00e4ugen.<\/p>\n<p>Die L\u00e4ufigkeit bei H\u00fcndinnen tritt 1-2x j\u00e4hrlich auf. W\u00e4hrenddessen verlieren sie Blut, das sich auch in den eigenen vier W\u00e4nden verteilen kann. Ob und inwieweit das der Fall ist, h\u00e4ngt davon ab, wie reinlich das jeweilige Tier ist. Spezielle H\u00f6schen k\u00f6nnen hier Abhilfe schaffen. Sie haben allerdings den Nachteil, dass sie die H\u00fcndin daran hindern, Reinlichkeit zu erlernen.<\/p>\n<h2><u>Kriterien zur Entscheidung<\/u><\/h2>\n<p>F\u00fcr welches Geschlecht man sich nun entscheiden sollte, l\u00e4sst sich nicht verallgemeinern. Wichtig ist, sich im Vorhinein gut zu \u00fcberlegen, worauf man am meisten Wert legt. W\u00fcnscht man sich zum Beispiel einen gehorsamen und unkomplizierten Hund, sollte man auch eine Rasse w\u00e4hlen, die diese Eigenschaften aufweist. Unabh\u00e4ngig davon ist es von Vorteil, ein Tier und dessen individuellen Charakter vorab unvoreingenommen kennenzulernen.<\/p>\n<p>Sollten Sie einen <a href=\"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/familienschutzhund-welche-hunderassen-sind-fuer-einen-familienschutzhund-geeignet\/\">Familienschutzhund<\/a> bei uns erwerben wollen, so werden wir dieses Thema vorab ausf\u00fchrlich mit Ihnen bespreche.<\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Die Entscheidung, einen Vierbeiner aufzunehmen oder anzuschaffen, wird h\u00e4ufig von der Frage begleitet: Welches Geschlecht passt zu mir? Doch ist diese nicht so einfach zu beantworten. Viele Vorurteile rangen sich um vermeintliche Eigenschaften, die&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":1788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-1786","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-hundeerziehung","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir? - Sp\u00fcrhundeschule Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afendis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/\"},\"author\":{\"name\":\"afendis\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/b66f573407551fd95616e6939ee52430\"},\"headline\":\"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir?\",\"datePublished\":\"2021-11-01T04:25:54+00:00\",\"dateModified\":\"2021-11-01T04:51:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/\"},\"wordCount\":563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/welcher-hund-passt-zu-mir.jpg\",\"articleSection\":[\"Hundeerziehung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/\",\"name\":\"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir? - Sp\u00fcrhundeschule Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/welcher-hund-passt-zu-mir.jpg\",\"datePublished\":\"2021-11-01T04:25:54+00:00\",\"dateModified\":\"2021-11-01T04:51:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/welcher-hund-passt-zu-mir.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/welcher-hund-passt-zu-mir.jpg\",\"width\":1920,\"height\":1275,\"caption\":\"welcher hund passt zu mir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/ruede-oder-huendin-welcher-hund-passt-zu-mir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"name\":\"Sp\u00fcrhundeschule Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\",\"name\":\"K9 Detection Dog School Germany GmbH\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"width\":148,\"height\":150,\"caption\":\"K9 Detection Dog School Germany GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/b66f573407551fd95616e6939ee52430\",\"name\":\"afendis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"caption\":\"afendis\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir? - Sp\u00fcrhundeschule Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/","twitter_misc":{"Verfasst von":"afendis","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#article","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/"},"author":{"name":"afendis","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/b66f573407551fd95616e6939ee52430"},"headline":"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir?","datePublished":"2021-11-01T04:25:54+00:00","dateModified":"2021-11-01T04:51:05+00:00","mainEntityOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/"},"wordCount":563,"commentCount":0,"publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/welcher-hund-passt-zu-mir.jpg","articleSection":["Hundeerziehung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/","url":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/","name":"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir? - Sp\u00fcrhundeschule Blog","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#primaryimage"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/welcher-hund-passt-zu-mir.jpg","datePublished":"2021-11-01T04:25:54+00:00","dateModified":"2021-11-01T04:51:05+00:00","breadcrumb":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#primaryimage","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/welcher-hund-passt-zu-mir.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/11\/welcher-hund-passt-zu-mir.jpg","width":1920,"height":1275,"caption":"welcher hund passt zu mir"},{"@type":"BreadcrumbList","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/ruede-oder-huendin-welcher-hund-passt-zu-mir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spuerhundeschule.de\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00fcde oder H\u00fcndin, welcher Hund passt zu mir?"}]},{"@type":"WebSite","@id":"https:\/\/spuerhundeschule.de\/blog\/#website","url":"https:\/\/spuerhundeschule.de\/blog\/","name":"Sp\u00fcrhundeschule Blog","description":"","publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spuerhundeschule.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spuerhundeschule.de\/blog\/#organization","name":"K9 Detection Dog School Germany GmbH","url":"https:\/\/spuerhundeschule.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","width":148,"height":150,"caption":"K9 Detection Dog School Germany GmbH"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/b66f573407551fd95616e6939ee52430","name":"afendis","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","caption":"afendis"}}]}},"_links":{"self":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/comments?post=1786"}],"version-history":[{"count":9,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1786\/revisions"}],"predecessor-version":[{"id":1797,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1786\/revisions\/1797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media\/1788"}],"wp:attachment":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media?parent=1786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/categories?post=1786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/tags?post=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}