{"id":1701,"date":"2021-01-18T04:27:32","date_gmt":"2021-01-18T04:27:32","guid":{"rendered":"https:\/\/spuerhundeschule.de\/blog\/?p=1701"},"modified":"2021-01-19T03:52:12","modified_gmt":"2021-01-19T02:52:12","slug":"was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht","status":"publish","type":"post","link":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/","title":{"rendered":"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht?"},"content":{"rendered":"<h2>Wie geht der eigene Hund nicht verloren?<\/h2>\n<div class=\"text-content\">\n<p>Einmal kurz nicht aufgepasst und dann der Schock &#8211; der Hund ist weg!<\/p>\n<p>Diese Szene ist f\u00fcr jeden Hundebesitzer der absolute Horror. Damit der eigene Hund nicht so leicht weglaufen kann oder auch schneller wieder gefunden werden kann, sollte man folgende Tipps beachten:<\/p>\n<h3>Zun\u00e4chst stellt sich die Frage, warum l\u00e4uft mein Hund eigentlich weg?<\/h3>\n<p>Die h\u00e4ufigsten Gr\u00fcnde sind, dass er von meinem Grundst\u00fcck weggelockt wird, er jagen geht, ein R\u00fcde einer l\u00e4ufigen H\u00fcndin hinterher rennt, er sich durch ein Ger\u00e4usch oder \u00c4hnliches erschreckt hat und gefl\u00fcchtet ist. Ein weiterer Grund kann auch sein, dass zwischen Hund und Besitzer keine richtige Bindung besteht und der Besitzer von dem Hund nicht als Rudelmitglied angesehen wird. Um ein Rudel zu finden oder sich aufzubauen, laufen dann die Hunde entsprechend weg.<\/p>\n<p>Damit er nicht vom eigenen Grundst\u00fcck ausb\u00fcxen kann, weil er etwas hinterher jagen m\u00f6chte oder \u00c4hnliches, und auch von au\u00dfen keiner ihn weglocken kann, sollte das eigene Grundst\u00fcck gut abgesichert sein. Beispielsweise kann man das Grundst\u00fcck mit einem entsprechend hohen und dichten Zaun begrenzen.<\/p>\n<p>Hunde, die einen ausgepr\u00e4gten Jagdtrieb haben, sollten insbesondere bei Spazierg\u00e4ngen im Wald und Feld nicht von der Leine genommen werden.<\/p>\n<p>Auch wenn der Hund im Normalfall auf das R\u00fcckrufkommando h\u00f6rt, ignoriert er im Jagdfieber dieses gerne.<\/p>\n<p>Dasselbe gilt entsprechend auf f\u00fcr R\u00fcden, die den Duft einer l\u00e4ufigen H\u00fcndin in der Nase haben.<\/p>\n<p>Das R\u00fcckrufkommando ignoriert er auch, wenn er zum Beispiel aus Angst fl\u00fcchtet. Wenn es laut knallt, kann der Hund aus Furcht davon laufen. Dies ist besonders gef\u00e4hrlich in Gebieten, die er nicht so gut kennt, da er dann oft den Weg nicht zur\u00fcck findet und sich verirrt.<\/p>\n<p>Deswegen ist es auch hier sinnvoll ihn angeleint zu lassen.<\/p>\n<p>Um dem Hund trotzdem einen gewissen Bewegungsfreiraum lassen zu k\u00f6nnen, empfehlen sich sogenannte &#8222;Schleppleinen&#8220;. Diese Leinen sind zwischen 5 und 15 Metern lang und lassen dem Hund mehr Freiheit als die handels\u00fcblichen Leinen, aber als Hundebesitzer hat man jederzeit die M\u00f6glichkeit einzugreifen und das Tier zu stoppen.<\/p>\n<p>Des Weiteren kann man seinen Hund chippen und im Hunderegister registrieren lassen, f\u00fcr den Fall, dass er doch einmal weglaufen sollte. Wenn der Hund gechippt und registriert ist, haben Fremde bzw. die Finder des Hundes die M\u00f6glichkeit, ihn durch einen Besuch beim Tierschutzverein, der Polizei oder einem Tierarzt wieder dem Besitzer zuordnen und diesen kontaktieren zu k\u00f6nnen.<\/p>\n<p>Wer allerdings seinem Hund keinen Chip einsetzen lassen m\u00f6chte, kann ihm zum Beispiel ein <a href=\"https:\/\/mypfote.com\/collections\/hundegeschirr\/Hundegeschirr\" target=\"_blank\" rel=\"noopener\">sogenanntes personalisiertes Hundegeschirr<\/a> anziehen, auf dem der Hundename sowie beispielsweise die Telefonnummer des Besitzers eingen\u00e4ht sind. Eine weitere M\u00f6glichkeit w\u00e4re entweder, genau wie beim Hundegeschirr, den Namen des Hundes sowie Kontaktdaten des Besitzers auf das normale Halsband zu n\u00e4hen oder ein <a href=\"https:\/\/mypfote.com\/collections\/hundehalsband-personalisiert-individuell-graviert\/Halsband\" target=\"_blank\" rel=\"noopener\">professionelles graviertes Hundehalsband<\/a> machen zu lassen, oder eine Hundemarke mit ebenfalls dem Namen des Hundes sowie Kontaktdaten des Besitzers an dem Hundehalsband zu befestigen.<\/p>\n<h3>Elektronische Hundehalsb\u00e4nder<\/h3>\n<p>Eine weiteren Idee f\u00fcr das schnelle finden seines Hundes sind GPS-Hundehalsb\u00e4nder. Mit diesen Halsb\u00e4ndern kann man \u00fcber eine App sehen, wo der Hund sich aufh\u00e4lt, und ihn entsprechend leicht verfolgen bzw. einfangen.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nkWwOA7s26\"><p><a href=\"https:\/\/spuerhundeschule.de\/blog\/hundeprofi-ausruestung\/hunde-peilsender-auf-der-basis-von-gps-ueber-mobilfunk\/\">Hunde Peilsender auf der Basis von GPS \u00fcber Mobilfunk<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Hunde Peilsender auf der Basis von GPS \u00fcber Mobilfunk&#8220; &#8212; Sp\u00fcrhundeschule Blog\" src=\"https:\/\/spuerhundeschule.de\/blog\/hundeprofi-ausruestung\/hunde-peilsender-auf-der-basis-von-gps-ueber-mobilfunk\/embed\/#?secret=j1KdrK7cC1#?secret=nkWwOA7s26\" data-secret=\"nkWwOA7s26\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Um ganz sicher zu gehen, kann man nat\u00fcrlich die letzten Punkte auch zusammen verwenden, also den Hund sowohl chippen und registrieren lassen als auch ihm beispielsweise eine Hundemarke anziehen.<\/p>\n<p>Wenn f\u00fcr das Weglaufen die fehlende Bindung der Grund ist, sollte man dringend an dieser arbeiten. Der Hund muss Vertrauen zu seinem Besitzer bekommen und ihn als Rudelmitglied wahrnehmen. Dies gelingt beispielsweise durch entspanntes Training und gemeinsam Zeit verbringen.<\/p>\n<\/div>\n ","protected":false},"excerpt":{"rendered":"<p>Wie geht der eigene Hund nicht verloren? Einmal kurz nicht aufgepasst und dann der Schock &#8211; der Hund ist weg! Diese Szene ist f\u00fcr jeden Hundebesitzer der absolute Horror. Damit der eigene Hund nicht&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":1707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-1701","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-hundeerziehung","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht? - Sp\u00fcrhundeschule Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"afendis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/\"},\"author\":{\"name\":\"afendis\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/b66f573407551fd95616e6939ee52430\"},\"headline\":\"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht?\",\"datePublished\":\"2021-01-18T04:27:32+00:00\",\"dateModified\":\"2021-01-19T02:52:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/\"},\"wordCount\":637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Arbeitsgeschirr-Canis.jpg\",\"articleSection\":[\"Hundeerziehung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/\",\"name\":\"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht? - Sp\u00fcrhundeschule Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Arbeitsgeschirr-Canis.jpg\",\"datePublished\":\"2021-01-18T04:27:32+00:00\",\"dateModified\":\"2021-01-19T02:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Arbeitsgeschirr-Canis.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Arbeitsgeschirr-Canis.jpg\",\"width\":862,\"height\":817},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/hundeerziehung\\\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"name\":\"Sp\u00fcrhundeschule Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#organization\",\"name\":\"K9 Detection Dog School Germany GmbH\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"contentUrl\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-spuerhundeschule.jpg\",\"width\":148,\"height\":150,\"caption\":\"K9 Detection Dog School Germany GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spuerhundeschule.de\\\/blog\\\/#\\\/schema\\\/person\\\/b66f573407551fd95616e6939ee52430\",\"name\":\"afendis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g\",\"caption\":\"afendis\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht? - Sp\u00fcrhundeschule Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/","twitter_misc":{"Verfasst von":"afendis","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#article","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/"},"author":{"name":"afendis","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/b66f573407551fd95616e6939ee52430"},"headline":"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht?","datePublished":"2021-01-18T04:27:32+00:00","dateModified":"2021-01-19T02:52:12+00:00","mainEntityOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/"},"wordCount":637,"commentCount":0,"publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/Arbeitsgeschirr-Canis.jpg","articleSection":["Hundeerziehung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/","url":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/","name":"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht? - Sp\u00fcrhundeschule Blog","isPartOf":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#primaryimage"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#primaryimage"},"thumbnailUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/Arbeitsgeschirr-Canis.jpg","datePublished":"2021-01-18T04:27:32+00:00","dateModified":"2021-01-19T02:52:12+00:00","breadcrumb":{"@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#primaryimage","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/Arbeitsgeschirr-Canis.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/Arbeitsgeschirr-Canis.jpg","width":862,"height":817},{"@type":"BreadcrumbList","@id":"https:\/\/spuerhundeschule.de\/blog\/hundeerziehung\/was-sollte-man-auf-jeden-fall-tun-damit-der-eigenen-hund-nicht-verloren-geht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spuerhundeschule.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Was sollte man auf jeden Fall tun, damit der eigenen Hund nicht verloren geht?"}]},{"@type":"WebSite","@id":"https:\/\/spuerhundeschule.de\/blog\/#website","url":"https:\/\/spuerhundeschule.de\/blog\/","name":"Sp\u00fcrhundeschule Blog","description":"","publisher":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spuerhundeschule.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spuerhundeschule.de\/blog\/#organization","name":"K9 Detection Dog School Germany GmbH","url":"https:\/\/spuerhundeschule.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","contentUrl":"https:\/\/spuerhundeschule.de\/blog\/wp-content\/uploads\/2021\/01\/logo-spuerhundeschule.jpg","width":148,"height":150,"caption":"K9 Detection Dog School Germany GmbH"},"image":{"@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/spuerhundeschule.de\/blog\/#\/schema\/person\/b66f573407551fd95616e6939ee52430","name":"afendis","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ab65fe634be3119ddb347939d05b571f04bc64331f52984ff4ef1f336045ff6?s=96&d=mm&r=g","caption":"afendis"}}]}},"_links":{"self":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/comments?post=1701"}],"version-history":[{"count":6,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1701\/revisions"}],"predecessor-version":[{"id":1710,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/posts\/1701\/revisions\/1710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media\/1707"}],"wp:attachment":[{"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/media?parent=1701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/categories?post=1701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spuerhundeschule.de\/blog\/wp-json\/wp\/v2\/tags?post=1701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}